{"id":141419,"date":"2025-03-24T16:48:47","date_gmt":"2025-03-24T20:48:47","guid":{"rendered":"https:\/\/lamaisonnee.org\/?p=141419"},"modified":"2025-07-21T13:30:13","modified_gmt":"2025-07-21T17:30:13","slug":"espace-parents","status":"publish","type":"post","link":"https:\/\/lamaisonnee.org\/fr\/espace-parents\/","title":{"rendered":"Espace Parents"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":4,"featured_media":141430,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[25],"class_list":["post-141419","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-article"],"acf":{"subtitle":"Un accompagnement sur mesure pour les familles immigrantes.","intro":"\u00catre parent, c\u2019est un cheminement constant, parfois rempli de d\u00e9fis, mais aussi d\u2019opportunit\u00e9s pour grandir avec ses enfants. Si vous \u00eates un parent immigr\u00e9, arriv\u00e9 au Qu\u00e9bec r\u00e9cemment, le programme Espace Parents est l\u00e0 pour vous offrir l'accompagnement dont vous avez besoin dans votre parcours de parentalit\u00e9.","text":"<p><a href=\"https:\/\/www.espace-parents.ca\/video-promotionnelle-espace-parents-5-min-26-sec\/\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-141426 size-large\" src=\"https:\/\/lamaisonnee.org\/wp-content\/uploads\/2025\/03\/Capture-decran-2025-03-24-161507-1024x540.png\" alt=\"\" width=\"1024\" height=\"540\" srcset=\"https:\/\/lamaisonnee.org\/wp-content\/uploads\/2025\/03\/Capture-decran-2025-03-24-161507-1024x540.png 1024w, https:\/\/lamaisonnee.org\/wp-content\/uploads\/2025\/03\/Capture-decran-2025-03-24-161507-300x158.png 300w, https:\/\/lamaisonnee.org\/wp-content\/uploads\/2025\/03\/Capture-decran-2025-03-24-161507-768x405.png 768w, https:\/\/lamaisonnee.org\/wp-content\/uploads\/2025\/03\/Capture-decran-2025-03-24-161507.png 1077w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/p>\n<p><strong><a href=\"https:\/\/lamaisonnee.org\/wp-content\/uploads\/2025\/03\/Publicite-Espace-parents-CHINOIS.pdf\" target=\"_blank\" rel=\"noopener\">\u6b32\u4e86\u89e3\u66f4\u591a\u4fe1\u606f\u5e76\u62a5\u540d<\/a><\/strong><\/p>\n<p>Qu&rsquo;est-ce qu&rsquo;Espace Parents ?<\/p>\n<p><strong>Espace Parents<\/strong> est un programme qui vise \u00e0 soutenir les parents immigr\u00e9s dans l\u2019adaptation \u00e0 leur nouvelle vie au Qu\u00e9bec. D\u00e9velopp\u00e9 en collaboration entre l\u2019Universit\u00e9 de Montr\u00e9al, le CIUSSS Centre-Sud, et le milieu communautaire, ce programme offre une s\u00e9rie de <strong>9 s\u00e9ances <\/strong>de 2 heures chacune.<br \/>\nLa <strong>Maisonn\u00e9e<\/strong>, partenaire essentiel de ce programme, travaille de pr\u00e8s avec Espace Parents pour former notre intervenante responsable du projet, qui sera l\u00e0 pour vous accompagner \u00e0 chaque \u00e9tape.<\/p>\n<p><strong>Un programme structur\u00e9 en 3 modules essentiels<\/strong><\/p>\n<p>Le programme <strong>Espace Parents<\/strong> est r\u00e9parti en 3 modules principaux, chacun traitant de sujets cl\u00e9s pour aider les parents \u00e0 mieux comprendre et soutenir leurs enfants dans leur d\u00e9veloppement.<\/p>\n<ol>\n<li><strong>Comprendre les impacts de l\u2019immigration sur la famille<\/strong><\/li>\n<\/ol>\n<p>L\u2019immigration est une exp\u00e9rience marquante, et elle peut avoir un impact profond sur la dynamique familiale. Ce module vous aide \u00e0 comprendre ces impacts et comment mieux g\u00e9rer les ajustements dans votre famille suite \u00e0 un changement culturel et g\u00e9ographique.<\/p>\n<ol start=\"2\">\n<li><strong>Identifier les besoins et l\u2019identit\u00e9 de vos enfants<\/strong><\/li>\n<\/ol>\n<p>Les enfants issus de familles immigrantes vivent des r\u00e9alit\u00e9s uniques. Ce module vous permet de mieux comprendre les besoins sp\u00e9cifiques de vos enfants, tout en les aidant \u00e0 d\u00e9velopper leur propre identit\u00e9 dans un nouveau pays et une nouvelle culture.<\/p>\n<ol start=\"3\">\n<li><strong>Mettre en place des strat\u00e9gies efficaces d\u2019encadrement et r\u00e9soudre les difficult\u00e9s parentales<\/strong><\/li>\n<\/ol>\n<p>Ce module pratique vous fournit des outils pour g\u00e9rer les d\u00e9fis quotidiens de la parentalit\u00e9, tout en mettant l\u2019accent sur l\u2019importance de l\u2019encadrement bienveillant et de la r\u00e9solution constructive des conflits familiaux.<\/p>\n<p><strong>Un certificat de participation \u00e0 la cl\u00e9 !<\/strong><\/p>\n<p>\u00c0 la fin de ce parcours, vous recevrez un <strong>certificat de participation<\/strong>, preuve de votre engagement dans le processus d\u2019apprentissage et d\u2019accompagnement parental.<\/p>\n<p><strong>Qui peut participer ?<\/strong><\/p>\n<p>Le programme est ouvert \u00e0 tous les parents qui r\u00e9pondent \u00e0 ces crit\u00e8res :<\/p>\n<ul>\n<li>Vous \u00eates parent d&rsquo;enfants \u00e2g\u00e9s de 5 \u00e0 17 ans ?<\/li>\n<li>Vous \u00eates issu(e) de l&rsquo;immigration et \u00eates arriv\u00e9(e) au Qu\u00e9bec depuis moins de 5 ans ?<\/li>\n<\/ul>\n<p>Si vous avez r\u00e9pondu \u00ab\u00a0OUI\u00a0\u00bb \u00e0 ces deux questions, vous \u00eates \u00e9ligible \u00e0 participer <strong>gratuitement<\/strong> au programme <strong>Espace Parents<\/strong>.<\/p>\n<p><strong><u>Note importante : <\/u><\/strong>Le programme n\u2019accepte pas les familles en situation d\u2019intervention de la <strong>DPJ<\/strong> (Direction de la protection de la jeunesse).<\/p>\n<p><strong>Quand commence le programme ?<\/strong><\/p>\n<p>Nous avons le plaisir de vous annoncer que la p\u00e9riode de cohorte en mandarin qui a eu un franc succ\u00e8s s&rsquo;ach\u00e8ve le 12 juillet. Cependant, la cohorte en fran\u00e7ais commence d\u00e8s le 26 juillet ! N&rsquo;attendez plus pour saisir cette opportunit\u00e9 de soutenir votre parcours parental.<\/p>\n<p><strong>Comment s\u2019inscrire ?<\/strong><\/p>\n<p>L&rsquo;inscription est simple et rapide ! Cliquez sur le lien ci-dessous pour acc\u00e9der au <a href=\"https:\/\/forms.office.com\/r\/56bEfimEzJ\" target=\"_blank\" rel=\"noopener\">formulaire d&rsquo;inscription en ligne ICI<\/a>.<\/p>\n<p>Une fois votre formulaire compl\u00e9t\u00e9, nous organiserons une <strong>rencontre personnelle<\/strong> (en pr\u00e9sentiel ou en ligne) pour discuter des d\u00e9tails du programme avant de finaliser votre inscription.<\/p>\n<p><strong>T\u00e9moignages de parents issus de la premi\u00e8re cohorte en mandarin qui s&rsquo;est termin\u00e9 le 12 juillet 2025 :<\/strong><\/p>\n<p><strong>Ping, p\u00e8re d\u2019une fille de 17 ans<\/strong>\u00a0:<\/p>\n<p>\u00ab\u00a0<em>Je tiens \u00e0 vous remercier sinc\u00e8rement pour votre aide et votre accompagnement pendant cette p\u00e9riode. Gr\u00e2ce aux ateliers Espace Parents, j\u2019ai appris beaucoup de choses utiles et j\u2019ai d\u00e9sormais plus de confiance pour vivre ici. J\u2019esp\u00e8re que mon enfant et moi pourrons apprendre le fran\u00e7ais avec succ\u00e8s dans un avenir proche, afin de mieux nous int\u00e9grer et de vivre plus sereinement ici.<\/em>\u00a0\u00bb<\/p>\n<p><strong>Xuefei, m\u00e8re d\u2019un gar\u00e7on de 2 ans<\/strong>\u00a0:<\/p>\n<p>\u00ab<em>\u00a0Je suis tr\u00e8s reconnaissante d\u2019avoir eu la chance de participer \u00e0 Espace Parents. Pendant ces deux mois, mes samedis ont \u00e9t\u00e9 remplis de joie et de satisfaction. J\u2019ai appris beaucoup de connaissances utiles sur la parentalit\u00e9 et j\u2019ai \u00e9galement nou\u00e9 de nouvelles amiti\u00e9s.<\/em><\/p>\n<p><em>Gr\u00e2ce \u00e0 Espace Parents, je me sens plus confiante et motiv\u00e9e pour accompagner la croissance de mon enfant. Je remercie chaleureusement la Maisonn\u00e9e d\u2019avoir organis\u00e9 cette cohorte d&rsquo;espace parents en chinois. Je tiens \u00e9galement \u00e0 exprimer ma profonde gratitude \u00e0 Madame Yu Yang, une personne exceptionnelle, toujours pr\u00eate \u00e0 aider les autres, son esprit d\u2019entraide m\u00e9rite d\u2019\u00eatre salu\u00e9. Je suis heureuse de l\u2019avoir rencontr\u00e9e.<\/em><\/p>\n<p><em>J\u2019esp\u00e8re que les futures cohortes d&rsquo;Espace parents pourront continuer \u00e0 aider encore plus de familles. <\/em>\u00bb<\/p>\n<p>Jingyi, maman d&rsquo;une fille de 12 ans :<\/p>\n<p>\u00ab<em> Les neuf semaines de formation dans le cadre du programme Espace Parents sont pass\u00e9es en un clin d\u2019\u0153il, mais les r\u00e9flexions et les transformations qu\u2019il m\u2019a apport\u00e9es continuent de se d\u00e9ployer doucement dans ma vie de tous les jours.\u00a0<\/em><em>En tant que parent nouvellement immigr\u00e9, confront\u00e9e \u00e0 un environnement compl\u00e8tement nouveau, j\u2019ai souvent \u00e9t\u00e9 travers\u00e9e par le doute : <\/em><em>Ma fa\u00e7on d\u2019\u00e9duquer est-elle la bonne ? <\/em><em>Ne devrais-je pas \u00eatre \u00ab\u00a0plus stricte\u00a0\u00bb, comme d\u2019autres le font ? <\/em><em>Les voix ext\u00e9rieures me rendaient parfois anxieuse et ind\u00e9cise.<\/em><br \/>\n<em>Dans Espace Parents, j\u2019ai trouv\u00e9 un point d\u2019ancrage solide qui m\u2019a permis de clarifier et d\u2019affirmer ma direction \u00e9ducative : respecter mon enfant, lui faire confiance, et grandir avec lui. Ces valeurs, je les connaissais d\u00e9j\u00e0, mais cette formation m\u2019a permis de les revisiter en profondeur et surtout, de confirmer que c\u2019est vraiment ce chemin-l\u00e0 que je choisis de suivre.<\/em><br \/>\n<em>Au fil de ces semaines, j\u2019ai acquis des outils concrets pour accompagner mon enfant, mais aussi une plus grande capacit\u00e9 \u00e0 accueillir les changements et les d\u00e9fis avec calme. En me lib\u00e9rant du regard des autres et de la pression des comparaisons, je me sens plus stable, plus sereine, et ma fille le ressent aussi. Elle ne porte plus mon ins\u00e9curit\u00e9 ; elle devient plus d\u00e9tendue, plus confiante.<\/em><br \/>\n<em>Pour notre famille qui est encore en train de s\u2019adapter \u00e0 une nouvelle vie ici, c\u2019est un tr\u00e8s bon d\u00e9part. Le changement commence chez les parents, puis rayonne \u00e0 travers l\u2019ambiance familiale. L\u2019enfant, naturellement, en b\u00e9n\u00e9ficie \u00e0 son tour. C\u2019est un processus doux, mais durable, un cercle vertueux qui me donne la conviction que, quels que soient les d\u00e9fis \u00e0 venir, nous serons capables d\u2019y faire face avec plus de confiance et de s\u00e9r\u00e9nit\u00e9. <\/em>\u00bb<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Plus d&rsquo;informations<\/strong><\/p>\n<p>Si vous avez des questions ou avez besoin de plus d\u2019informations, n\u2019h\u00e9sitez pas \u00e0 contacter <strong>Mme Yang YU<\/strong> par courriel \u00e0 : <strong>yang.yu@lamaisonnee.org<\/strong><\/p>\n<p>L\u2019\u00e9quipe de <strong>La Maisonn\u00e9e<\/strong> est l\u00e0 pour vous offrir un v\u00e9ritable soutien et un <strong>filet de s\u00e9curit\u00e9<\/strong> dans votre parcours de parentalit\u00e9. Nous sommes impatients de vous accompagner dans cette belle aventure !<\/p>\n<p><em>La Maisonn\u00e9e est l\u00e0 pour vous soutenir \u00e0 chaque \u00e9tape du chemin !<\/em><\/p>\n","author":"","link":""},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Espace Parents - La Maisonn\u00e9e<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lamaisonnee.org\/fr\/espace-parents\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Espace Parents - La Maisonn\u00e9e\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lamaisonnee.org\/fr\/espace-parents\/\" \/>\n<meta property=\"og:site_name\" content=\"La Maisonn\u00e9e\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-24T20:48:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-21T17:30:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lamaisonnee.org\/wp-content\/uploads\/2025\/03\/8932-4_MAJ_BANDEAU_ESPACE_PARENT_1080X1080_FR_TEXTE2_VF-e1742849125387.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2250\" \/>\n\t<meta property=\"og:image:height\" content=\"1870\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ines Bouteiller\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ines Bouteiller\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lamaisonnee.org\\\/fr\\\/espace-parents\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lamaisonnee.org\\\/fr\\\/espace-parents\\\/\"},\"author\":{\"name\":\"Ines Bouteiller\",\"@id\":\"https:\\\/\\\/lamaisonnee.org\\\/fr\\\/#\\\/schema\\\/person\\\/bfcd9793366ce038e85993007fa36431\"},\"headline\":\"Espace Parents\",\"datePublished\":\"2025-03-24T20:48:47+00:00\",\"dateModified\":\"2025-07-21T17:30:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lamaisonnee.org\\\/fr\\\/espace-parents\\\/\"},\"wordCount\":2,\"image\":{\"@id\":\"https:\\\/\\\/lamaisonnee.org\\\/fr\\\/espace-parents\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lamaisonnee.org\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/8932-4_MAJ_BANDEAU_ESPACE_PARENT_1080X1080_FR_TEXTE2_VF-e1742849125387.jpg\",\"articleSection\":[\"Article\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lamaisonnee.org\\\/fr\\\/espace-parents\\\/\",\"url\":\"https:\\\/\\\/lamaisonnee.org\\\/fr\\\/espace-parents\\\/\",\"name\":\"Espace Parents - La Maisonn\u00e9e\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lamaisonnee.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lamaisonnee.org\\\/fr\\\/espace-parents\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lamaisonnee.org\\\/fr\\\/espace-parents\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lamaisonnee.org\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/8932-4_MAJ_BANDEAU_ESPACE_PARENT_1080X1080_FR_TEXTE2_VF-e1742849125387.jpg\",\"datePublished\":\"2025-03-24T20:48:47+00:00\",\"dateModified\":\"2025-07-21T17:30:13+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/lamaisonnee.org\\\/fr\\\/#\\\/schema\\\/person\\\/bfcd9793366ce038e85993007fa36431\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lamaisonnee.org\\\/fr\\\/espace-parents\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lamaisonnee.org\\\/fr\\\/espace-parents\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lamaisonnee.org\\\/fr\\\/espace-parents\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lamaisonnee.org\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/8932-4_MAJ_BANDEAU_ESPACE_PARENT_1080X1080_FR_TEXTE2_VF-e1742849125387.jpg\",\"contentUrl\":\"https:\\\/\\\/lamaisonnee.org\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/8932-4_MAJ_BANDEAU_ESPACE_PARENT_1080X1080_FR_TEXTE2_VF-e1742849125387.jpg\",\"width\":2250,\"height\":1870},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lamaisonnee.org\\\/fr\\\/espace-parents\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/lamaisonnee.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Espace Parents\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lamaisonnee.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/lamaisonnee.org\\\/fr\\\/\",\"name\":\"La Maisonn\u00e9e\",\"description\":\"Aide aux immigrants\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lamaisonnee.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lamaisonnee.org\\\/fr\\\/#\\\/schema\\\/person\\\/bfcd9793366ce038e85993007fa36431\",\"name\":\"Ines Bouteiller\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e7c0c90f01f6e7c3a5ec4fd5c4c31f3b4f846890cb1bfdac38bfcf0452991011?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e7c0c90f01f6e7c3a5ec4fd5c4c31f3b4f846890cb1bfdac38bfcf0452991011?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e7c0c90f01f6e7c3a5ec4fd5c4c31f3b4f846890cb1bfdac38bfcf0452991011?s=96&d=mm&r=g\",\"caption\":\"Ines Bouteiller\"},\"url\":\"https:\\\/\\\/lamaisonnee.org\\\/fr\\\/author\\\/ines_lamaisonnee\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Espace Parents - La Maisonn\u00e9e","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lamaisonnee.org\/fr\/espace-parents\/","og_locale":"fr_FR","og_type":"article","og_title":"Espace Parents - La Maisonn\u00e9e","og_url":"https:\/\/lamaisonnee.org\/fr\/espace-parents\/","og_site_name":"La Maisonn\u00e9e","article_published_time":"2025-03-24T20:48:47+00:00","article_modified_time":"2025-07-21T17:30:13+00:00","og_image":[{"width":2250,"height":1870,"url":"https:\/\/lamaisonnee.org\/wp-content\/uploads\/2025\/03\/8932-4_MAJ_BANDEAU_ESPACE_PARENT_1080X1080_FR_TEXTE2_VF-e1742849125387.jpg","type":"image\/jpeg"}],"author":"Ines Bouteiller","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Ines Bouteiller","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lamaisonnee.org\/fr\/espace-parents\/#article","isPartOf":{"@id":"https:\/\/lamaisonnee.org\/fr\/espace-parents\/"},"author":{"name":"Ines Bouteiller","@id":"https:\/\/lamaisonnee.org\/fr\/#\/schema\/person\/bfcd9793366ce038e85993007fa36431"},"headline":"Espace Parents","datePublished":"2025-03-24T20:48:47+00:00","dateModified":"2025-07-21T17:30:13+00:00","mainEntityOfPage":{"@id":"https:\/\/lamaisonnee.org\/fr\/espace-parents\/"},"wordCount":2,"image":{"@id":"https:\/\/lamaisonnee.org\/fr\/espace-parents\/#primaryimage"},"thumbnailUrl":"https:\/\/lamaisonnee.org\/wp-content\/uploads\/2025\/03\/8932-4_MAJ_BANDEAU_ESPACE_PARENT_1080X1080_FR_TEXTE2_VF-e1742849125387.jpg","articleSection":["Article"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/lamaisonnee.org\/fr\/espace-parents\/","url":"https:\/\/lamaisonnee.org\/fr\/espace-parents\/","name":"Espace Parents - La Maisonn\u00e9e","isPartOf":{"@id":"https:\/\/lamaisonnee.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lamaisonnee.org\/fr\/espace-parents\/#primaryimage"},"image":{"@id":"https:\/\/lamaisonnee.org\/fr\/espace-parents\/#primaryimage"},"thumbnailUrl":"https:\/\/lamaisonnee.org\/wp-content\/uploads\/2025\/03\/8932-4_MAJ_BANDEAU_ESPACE_PARENT_1080X1080_FR_TEXTE2_VF-e1742849125387.jpg","datePublished":"2025-03-24T20:48:47+00:00","dateModified":"2025-07-21T17:30:13+00:00","author":{"@id":"https:\/\/lamaisonnee.org\/fr\/#\/schema\/person\/bfcd9793366ce038e85993007fa36431"},"breadcrumb":{"@id":"https:\/\/lamaisonnee.org\/fr\/espace-parents\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lamaisonnee.org\/fr\/espace-parents\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lamaisonnee.org\/fr\/espace-parents\/#primaryimage","url":"https:\/\/lamaisonnee.org\/wp-content\/uploads\/2025\/03\/8932-4_MAJ_BANDEAU_ESPACE_PARENT_1080X1080_FR_TEXTE2_VF-e1742849125387.jpg","contentUrl":"https:\/\/lamaisonnee.org\/wp-content\/uploads\/2025\/03\/8932-4_MAJ_BANDEAU_ESPACE_PARENT_1080X1080_FR_TEXTE2_VF-e1742849125387.jpg","width":2250,"height":1870},{"@type":"BreadcrumbList","@id":"https:\/\/lamaisonnee.org\/fr\/espace-parents\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/lamaisonnee.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Espace Parents"}]},{"@type":"WebSite","@id":"https:\/\/lamaisonnee.org\/fr\/#website","url":"https:\/\/lamaisonnee.org\/fr\/","name":"La Maisonn\u00e9e","description":"Aide aux immigrants","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lamaisonnee.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/lamaisonnee.org\/fr\/#\/schema\/person\/bfcd9793366ce038e85993007fa36431","name":"Ines Bouteiller","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/e7c0c90f01f6e7c3a5ec4fd5c4c31f3b4f846890cb1bfdac38bfcf0452991011?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e7c0c90f01f6e7c3a5ec4fd5c4c31f3b4f846890cb1bfdac38bfcf0452991011?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e7c0c90f01f6e7c3a5ec4fd5c4c31f3b4f846890cb1bfdac38bfcf0452991011?s=96&d=mm&r=g","caption":"Ines Bouteiller"},"url":"https:\/\/lamaisonnee.org\/fr\/author\/ines_lamaisonnee\/"}]}},"_links":{"self":[{"href":"https:\/\/lamaisonnee.org\/fr\/wp-json\/wp\/v2\/posts\/141419","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lamaisonnee.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lamaisonnee.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lamaisonnee.org\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/lamaisonnee.org\/fr\/wp-json\/wp\/v2\/comments?post=141419"}],"version-history":[{"count":14,"href":"https:\/\/lamaisonnee.org\/fr\/wp-json\/wp\/v2\/posts\/141419\/revisions"}],"predecessor-version":[{"id":147455,"href":"https:\/\/lamaisonnee.org\/fr\/wp-json\/wp\/v2\/posts\/141419\/revisions\/147455"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lamaisonnee.org\/fr\/wp-json\/wp\/v2\/media\/141430"}],"wp:attachment":[{"href":"https:\/\/lamaisonnee.org\/fr\/wp-json\/wp\/v2\/media?parent=141419"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lamaisonnee.org\/fr\/wp-json\/wp\/v2\/categories?post=141419"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}