{"id":1158,"date":"2022-05-30T16:04:35","date_gmt":"2022-05-30T20:04:35","guid":{"rendered":"https:\/\/lamaisonnee.org\/?p=1158"},"modified":"2023-05-24T12:11:20","modified_gmt":"2023-05-24T16:11:20","slug":"la-cite-inclusive","status":"publish","type":"post","link":"https:\/\/lamaisonnee.org\/fr\/la-cite-inclusive\/","title":{"rendered":"La cit\u00e9 inclusive"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":1302,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[25],"class_list":["post-1158","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-article"],"acf":{"subtitle":"Connaissez-vous ce qu'est l'Inclusion ?","intro":"Nous vous invitons \u00e0 d\u00e9couvrir le projet Cit\u00e9 Inclusive !","text":"<h2><strong>Projet : Cit\u00e9 Inclusive &#8211; Projet concert\u00e9<\/strong><\/h2>\n<p>Comment vivre la diversit\u00e9 en favorisant les relations harmonieuses entre les cultures et faciliter l\u2019int\u00e9gration des immigrants?<br \/>\nLes minorit\u00e9s culturelles ont contribu\u00e9 \u00e0 la vitalit\u00e9 \u00e9conomique, sociale et identitaire du Qu\u00e9bec, notamment par leur esprit d\u2019entreprise. Il y a peu de secteurs o\u00f9 elles n\u2019ont pas laiss\u00e9 leur marque. Les universit\u00e9s et les h\u00f4pitaux qu\u00e9b\u00e9cois, par exemple, ont b\u00e9n\u00e9fici\u00e9 de leur apport. La pr\u00e9sence des artistes identifi\u00e9s \u00e0 ces minorit\u00e9s dans tous les domaines a eu un impact essentiel sur le d\u00e9veloppement de la culture qu\u00e9b\u00e9coise. Il faut aussi souligner le d\u00e9veloppement des sports professionnels et amateurs. Le travail collectif du Qu\u00e9bec dans le secteur de la justice et des droits de la personne a \u00e9t\u00e9 le produit d\u2019une collaboration soutenue entre la majorit\u00e9 et les minorit\u00e9s. Au Qu\u00e9bec la soci\u00e9t\u00e9 a b\u00e9n\u00e9fici\u00e9 de sa diversit\u00e9 qui est sans doute une de ses caract\u00e9ristiques fondamentales.<\/p>\n<p><strong>Les objectifs de ce projet :<\/strong><\/p>\n<ul>\n<li>Am\u00e9liorer chez les personnes immigrantes et membres des communaut\u00e9s culturelles ainsi que chez les membres de la soci\u00e9t\u00e9 d\u2019accueil une meilleure connaissance et compr\u00e9hension des us et coutumes de chacun dans le but de maintenir des relations interculturelles pacifiques et harmonieuses;<\/li>\n<li>D\u00e9velopper des ateliers de formation pour les organismes en g\u00e9n\u00e9ral et particuli\u00e8rement aux organismes communautaires qui viennent en aide aux immigrants;<\/li>\n<li>Sensibiliser les organismes publics parapublics et communautaires \u00e0 la r\u00e9alit\u00e9 de l\u2019immigration;<\/li>\n<li>D\u00e9velopper une expertise dans les relations interculturelles capables d\u2019offrir un support ponctuel et une assistance imm\u00e9diate en situation de crise;<\/li>\n<li>Favoriser une meilleure insertion sociale chez les personnes immigrantes et membres des communaut\u00e9s culturelles;<\/li>\n<li>Sensibiliser la population de Montr\u00e9al aux diff\u00e9rences culturelles par l\u2019interm\u00e9diaire de s\u00e9ances de sensibilisation offerte aux usagers des services publics et communautaires;<\/li>\n<li>Organiser des activit\u00e9s de sensibilisation interculturelles<\/li>\n<\/ul>\n<h3><strong>Nos partenaires<\/strong><\/h3>\n<p><strong>Le LABRRI<\/strong><br \/>\nCr\u00e9\u00e9 en 2010, le LABRRI r\u00e9unit des chercheurs, des intervenants et des \u00e9tudiants qui s\u2019int\u00e9ressent aux dynamiques des relations sociales en contexte interculturel. Notre programme de travail, qui se veut un croisement de la recherche fondamentale et de la recherche appliqu\u00e9e, met \u00e0 profit aussi bien les avanc\u00e9es de la connaissance dans les domaines de recherche en sciences humaines, que l\u2019expertise et les savoirs communautaires et institutionnels (pour voir une description d\u00e9taill\u00e9e des axes de recherche: http:\/\/labrri.net\/recherche\/axes-de-recherche\/). Dans l\u2019ensemble de nos activit\u00e9s, nous voulons comprendre de fa\u00e7on empirique les enjeux historiques et politiques de la r\u00e9alit\u00e9 plurielle qui caract\u00e9risent les soci\u00e9t\u00e9s contemporaines, mais aussi les pr\u00e9suppos\u00e9s \u00e9pist\u00e9mologiques de toute discipline qui a contribu\u00e9 \u00e0 la recherche interculturelle (l\u2019anthropologie, la philosophie, la psychologie, les sciences politiques, la communication, la sociologie, etc.).<\/p>\n<p><strong>Chaire de recherche du Canada<\/strong><br \/>\nCommunication interculturelles et technologies de gestion en contexte pluraliste<br \/>\nLes travaux de la chaire visent l\u2019identification et la compr\u00e9hension des diff\u00e9rentes articulations pr\u00e9sentes entre les technologies de gestion de la population (c.-\u00e0-d., la tendance au contr\u00f4le et \u00e0 la surveillance par divers moyens) et la communication interculturelle. Jorge Frozzini, professeur \u00e0 l\u2019UQAC et titulaire de la chaire, vous invite \u00e0 explorer le site web (https:\/\/intercultureltechnologies.ca\/) et la page Facebook (https:\/\/www.facebook.com\/CRC.CITG\/) et \u00e0 vous abonner \u00e0 l\u2019infolettre afin de suivre les travaux et recevoir les derni\u00e8res nouvelles.<\/p>\n<p><strong>Les r\u00e9alisations &#8211; Ateliers de situations interculturelles<\/strong><\/p>\n<p>Organisation de plusieurs ateliers pour les intervenant.e.s communautaires : initiation \u00e0 l\u2019interculturel et ateliers de situations interculturelles, anim\u00e9s par l\u2019\u00e9quipe du LABRRI. La r\u00e9flexion propos\u00e9e par l\u2019atelier cherche \u00e0 offrir des r\u00e9ponses aux trois questions suivantes : \u2013 Quelles situations interculturelles probl\u00e9matiques voyons-nous sur le terrain ? \u2013 Quels outils sont \u00e0 notre port\u00e9e pour r\u00e9pondre \u00e0 ces situations ? \u2013 Sur quels cadres d\u2019analyse nous appuyons-nous pour orienter nos actions ? \u00c0 la fin de cet atelier, les participant.es ont \u00e9t\u00e9 en mesure de : 1. Donner une d\u00e9finition de l\u2019approche interculturelle et se situer par rapport \u00e0 cette approche 2. Identifier et d\u00e9crire un certain nombre de situations en contexte interculturel 3. Appliquer des outils qui permettent d\u2019aller envers des solutions concr\u00e8tes. Les ateliers \u00e9taient gratuits d\u2019une dur\u00e9e de trois heures.<\/p>\n<p><strong>Le colloque du 12 mai 2022 &#8211; Une cit\u00e9 inclusive<\/strong><\/p>\n<p>La Maisonn\u00e9e a organis\u00e9 en date du 12 mai dernier un colloque portant sur le th\u00e8me : Une cit\u00e9 inclusive. Cette activit\u00e9 de r\u00e9flexion et de mobilisation des connaissances autour de la probl\u00e9matique de l\u2019inclusion, a connu la participation de plus de 90 personnes appartenant \u00e0 des organismes communautaires de Montr\u00e9al, des chercheurs du laboratoire de recherche en relations interculturelles (LABRRI) et de la chaire de recherche du Canada, en plus des employ\u00e9.e.s de la ville de Montr\u00e9al et de La Maisonn\u00e9e.<br \/>\nL\u2019objectif de ce colloque \u00e9tait de partager la r\u00e9flexion que La Maisonn\u00e9e m\u00e8ne depuis quelques ann\u00e9es sur cette probl\u00e9matique, notamment dans le cadre de la collaboration avec le LABRRI. Ainsi, la journ\u00e9e a \u00e9t\u00e9 marqu\u00e9e par une conf\u00e9rence d\u2019ouverture de la Commissaire du Bureau de lutte contre le racisme et les discriminations syst\u00e9miques de Montr\u00e9al, Madame Bochra Manai, qui est revenue sur l\u2019exp\u00e9rience de la ville en mati\u00e8re d\u2019inclusion. S\u2019en sont suivi des expos\u00e9s sur la collaboration entre le LABRRI et La Maisonn\u00e9e, l\u2019exp\u00e9rience de l\u2019inclusiom\u00e8tre et d\u2019autres outils de l\u2019inclusion, d\u00e9velopp\u00e9s par la chaire de recherche du Canada. Ces expos\u00e9s ont connu une forte interaction du public pr\u00e9sent, qui n\u2019a pas manqu\u00e9 d\u2019alimenter les contenus des intervenants de t\u00e9moignages pluriels de pratiques inclusives et de quelques enjeux que pr\u00e9sentent les situations d\u2019exclusion.<br \/>\nLa projection de deux capsules vid\u00e9o produites par La Maisonn\u00e9e sur les th\u00e8mes : \u00ab Une cit\u00e9 inclusive \u00bb et \u00ab D\u2019o\u00f9 viens-tu? \u00bb, ont permis de mettre en lumi\u00e8re d\u2019autres angles morts de la r\u00e9flexion sur les formes de discrimination qui traversent l\u2019espace public montr\u00e9alais. Ces capsules ont \u00e9t\u00e9 diffus\u00e9es \u00e0 la suite des travaux de colloque pour rendre visibles ces points de vue capt\u00e9s par La Maisonn\u00e9e.<\/p>\n<p>Dans cette premi\u00e8re vid\u00e9o nous d\u00e9couvrirons les perceptions que se font des intervenant.e.s communautaires de l\u2019inclusion \u00e0 Montr\u00e9al.<br \/>\n<a href=\"https:\/\/youtu.be\/u_ghrm0jE88\" target=\"_blank\" rel=\"noopener\">Bon visionnage Youtube<\/a><\/p>\n<p>Cette seconde vid\u00e9o aborde un des aspects de nos interactions quotidiennes \u00e0 Montr\u00e9al \u00e0 travers la question : d\u2019o\u00f9 viens-tu ? Cette interrogation conduit les interlocuteurs et interlocutrices \u00e0 r\u00e9activer certains aspects de leur identit\u00e9, ce qui est de nature \u00e0 ouvrir le d\u00e9bat soit sur un \u00e9change inclusif ou une interaction qui pourrait exclure.<br \/>\n<a href=\"https:\/\/youtu.be\/cl5wCEiueiw\" target=\"_blank\" rel=\"noopener\">Bon visionnage<\/a><\/p>\n","author":"","link":{"title":"Consultez les Actes du colloque complet pour conna\u00eetre les r\u00e9sultats du projet !","url":"https:\/\/lamaisonnee.org\/wp-content\/uploads\/2022\/05\/Actes-du-Colloque-annuel-de-La-Maisonne\u0301e-2022_avec-photosv2.pdf","target":"_blank"}},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La cit\u00e9 inclusive - La Maisonn\u00e9e<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lamaisonnee.org\/fr\/la-cite-inclusive\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La cit\u00e9 inclusive - La Maisonn\u00e9e\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lamaisonnee.org\/fr\/la-cite-inclusive\/\" \/>\n<meta property=\"og:site_name\" content=\"La Maisonn\u00e9e\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-30T20:04:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-24T16:11:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lamaisonnee.org\/wp-content\/uploads\/2022\/05\/Colloque-Cite\u0301-inclusive-2022.4-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"D\u00e9veloppeur\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"D\u00e9veloppeur\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lamaisonnee.org\\\/fr\\\/la-cite-inclusive\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lamaisonnee.org\\\/fr\\\/la-cite-inclusive\\\/\"},\"author\":{\"name\":\"D\u00e9veloppeur\",\"@id\":\"https:\\\/\\\/lamaisonnee.org\\\/fr\\\/#\\\/schema\\\/person\\\/5b6ff30e69be0a76c93736ae5d2a5307\"},\"headline\":\"La cit\u00e9 inclusive\",\"datePublished\":\"2022-05-30T20:04:35+00:00\",\"dateModified\":\"2023-05-24T16:11:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lamaisonnee.org\\\/fr\\\/la-cite-inclusive\\\/\"},\"wordCount\":3,\"image\":{\"@id\":\"https:\\\/\\\/lamaisonnee.org\\\/fr\\\/la-cite-inclusive\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lamaisonnee.org\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Colloque-Cite\u0301-inclusive-2022.4-scaled.jpg\",\"articleSection\":[\"Article\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lamaisonnee.org\\\/fr\\\/la-cite-inclusive\\\/\",\"url\":\"https:\\\/\\\/lamaisonnee.org\\\/fr\\\/la-cite-inclusive\\\/\",\"name\":\"La cit\u00e9 inclusive - La Maisonn\u00e9e\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lamaisonnee.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lamaisonnee.org\\\/fr\\\/la-cite-inclusive\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lamaisonnee.org\\\/fr\\\/la-cite-inclusive\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lamaisonnee.org\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Colloque-Cite\u0301-inclusive-2022.4-scaled.jpg\",\"datePublished\":\"2022-05-30T20:04:35+00:00\",\"dateModified\":\"2023-05-24T16:11:20+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/lamaisonnee.org\\\/fr\\\/#\\\/schema\\\/person\\\/5b6ff30e69be0a76c93736ae5d2a5307\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lamaisonnee.org\\\/fr\\\/la-cite-inclusive\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lamaisonnee.org\\\/fr\\\/la-cite-inclusive\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lamaisonnee.org\\\/fr\\\/la-cite-inclusive\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lamaisonnee.org\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Colloque-Cite\u0301-inclusive-2022.4-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/lamaisonnee.org\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Colloque-Cite\u0301-inclusive-2022.4-scaled.jpg\",\"width\":2560,\"height\":1707},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lamaisonnee.org\\\/fr\\\/la-cite-inclusive\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/lamaisonnee.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La cit\u00e9 inclusive\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lamaisonnee.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/lamaisonnee.org\\\/fr\\\/\",\"name\":\"La Maisonn\u00e9e\",\"description\":\"Aide aux immigrants\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lamaisonnee.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lamaisonnee.org\\\/fr\\\/#\\\/schema\\\/person\\\/5b6ff30e69be0a76c93736ae5d2a5307\",\"name\":\"D\u00e9veloppeur\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ae0607ec60516fe0a28b4113b9686922ad23817caad9bef1c9e5754b4267efb3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ae0607ec60516fe0a28b4113b9686922ad23817caad9bef1c9e5754b4267efb3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ae0607ec60516fe0a28b4113b9686922ad23817caad9bef1c9e5754b4267efb3?s=96&d=mm&r=g\",\"caption\":\"D\u00e9veloppeur\"},\"url\":\"https:\\\/\\\/lamaisonnee.org\\\/fr\\\/author\\\/hamak\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La cit\u00e9 inclusive - La Maisonn\u00e9e","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lamaisonnee.org\/fr\/la-cite-inclusive\/","og_locale":"fr_FR","og_type":"article","og_title":"La cit\u00e9 inclusive - La Maisonn\u00e9e","og_url":"https:\/\/lamaisonnee.org\/fr\/la-cite-inclusive\/","og_site_name":"La Maisonn\u00e9e","article_published_time":"2022-05-30T20:04:35+00:00","article_modified_time":"2023-05-24T16:11:20+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/lamaisonnee.org\/wp-content\/uploads\/2022\/05\/Colloque-Cite\u0301-inclusive-2022.4-scaled.jpg","type":"image\/jpeg"}],"author":"D\u00e9veloppeur","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"D\u00e9veloppeur"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lamaisonnee.org\/fr\/la-cite-inclusive\/#article","isPartOf":{"@id":"https:\/\/lamaisonnee.org\/fr\/la-cite-inclusive\/"},"author":{"name":"D\u00e9veloppeur","@id":"https:\/\/lamaisonnee.org\/fr\/#\/schema\/person\/5b6ff30e69be0a76c93736ae5d2a5307"},"headline":"La cit\u00e9 inclusive","datePublished":"2022-05-30T20:04:35+00:00","dateModified":"2023-05-24T16:11:20+00:00","mainEntityOfPage":{"@id":"https:\/\/lamaisonnee.org\/fr\/la-cite-inclusive\/"},"wordCount":3,"image":{"@id":"https:\/\/lamaisonnee.org\/fr\/la-cite-inclusive\/#primaryimage"},"thumbnailUrl":"https:\/\/lamaisonnee.org\/wp-content\/uploads\/2022\/05\/Colloque-Cite\u0301-inclusive-2022.4-scaled.jpg","articleSection":["Article"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/lamaisonnee.org\/fr\/la-cite-inclusive\/","url":"https:\/\/lamaisonnee.org\/fr\/la-cite-inclusive\/","name":"La cit\u00e9 inclusive - La Maisonn\u00e9e","isPartOf":{"@id":"https:\/\/lamaisonnee.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lamaisonnee.org\/fr\/la-cite-inclusive\/#primaryimage"},"image":{"@id":"https:\/\/lamaisonnee.org\/fr\/la-cite-inclusive\/#primaryimage"},"thumbnailUrl":"https:\/\/lamaisonnee.org\/wp-content\/uploads\/2022\/05\/Colloque-Cite\u0301-inclusive-2022.4-scaled.jpg","datePublished":"2022-05-30T20:04:35+00:00","dateModified":"2023-05-24T16:11:20+00:00","author":{"@id":"https:\/\/lamaisonnee.org\/fr\/#\/schema\/person\/5b6ff30e69be0a76c93736ae5d2a5307"},"breadcrumb":{"@id":"https:\/\/lamaisonnee.org\/fr\/la-cite-inclusive\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lamaisonnee.org\/fr\/la-cite-inclusive\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lamaisonnee.org\/fr\/la-cite-inclusive\/#primaryimage","url":"https:\/\/lamaisonnee.org\/wp-content\/uploads\/2022\/05\/Colloque-Cite\u0301-inclusive-2022.4-scaled.jpg","contentUrl":"https:\/\/lamaisonnee.org\/wp-content\/uploads\/2022\/05\/Colloque-Cite\u0301-inclusive-2022.4-scaled.jpg","width":2560,"height":1707},{"@type":"BreadcrumbList","@id":"https:\/\/lamaisonnee.org\/fr\/la-cite-inclusive\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/lamaisonnee.org\/fr\/"},{"@type":"ListItem","position":2,"name":"La cit\u00e9 inclusive"}]},{"@type":"WebSite","@id":"https:\/\/lamaisonnee.org\/fr\/#website","url":"https:\/\/lamaisonnee.org\/fr\/","name":"La Maisonn\u00e9e","description":"Aide aux immigrants","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lamaisonnee.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/lamaisonnee.org\/fr\/#\/schema\/person\/5b6ff30e69be0a76c93736ae5d2a5307","name":"D\u00e9veloppeur","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/ae0607ec60516fe0a28b4113b9686922ad23817caad9bef1c9e5754b4267efb3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ae0607ec60516fe0a28b4113b9686922ad23817caad9bef1c9e5754b4267efb3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ae0607ec60516fe0a28b4113b9686922ad23817caad9bef1c9e5754b4267efb3?s=96&d=mm&r=g","caption":"D\u00e9veloppeur"},"url":"https:\/\/lamaisonnee.org\/fr\/author\/hamak\/"}]}},"_links":{"self":[{"href":"https:\/\/lamaisonnee.org\/fr\/wp-json\/wp\/v2\/posts\/1158","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lamaisonnee.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lamaisonnee.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lamaisonnee.org\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/lamaisonnee.org\/fr\/wp-json\/wp\/v2\/comments?post=1158"}],"version-history":[{"count":9,"href":"https:\/\/lamaisonnee.org\/fr\/wp-json\/wp\/v2\/posts\/1158\/revisions"}],"predecessor-version":[{"id":3183,"href":"https:\/\/lamaisonnee.org\/fr\/wp-json\/wp\/v2\/posts\/1158\/revisions\/3183"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lamaisonnee.org\/fr\/wp-json\/wp\/v2\/media\/1302"}],"wp:attachment":[{"href":"https:\/\/lamaisonnee.org\/fr\/wp-json\/wp\/v2\/media?parent=1158"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lamaisonnee.org\/fr\/wp-json\/wp\/v2\/categories?post=1158"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}