{"id":304,"date":"2023-04-27T18:35:47","date_gmt":"2023-04-27T22:35:47","guid":{"rendered":"https:\/\/lamaisonnee.org?post_type=partners&#038;p=304"},"modified":"2023-05-09T14:17:07","modified_gmt":"2023-05-09T18:17:07","slug":"desjardins","status":"publish","type":"partners","link":"https:\/\/lamaisonnee.org\/fr\/partners\/desjardins\/","title":{"rendered":"Caisses du C\u0153ur de l\u2019Ile \u2013 F\u00e9d\u00e9ration des Caisses Desjardins du Qu\u00e9bec"},"template":"","meta":{"_acf_changed":false},"cat_partner":[17,16],"class_list":["post-304","partners","type-partners","status-publish","hentry","cat_partner-bailleur-de-fonds","cat_partner-partenaire"],"acf":{"link":"https:\/\/www.desjardins.com\/index.jsp","icon":"https:\/\/lamaisonnee.org\/wp-content\/uploads\/2023\/04\/Desjardins.png"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Caisses du C\u0153ur de l\u2019Ile \u2013 F\u00e9d\u00e9ration des Caisses Desjardins du Qu\u00e9bec - La Maisonn\u00e9e<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Caisses du C\u0153ur de l\u2019Ile \u2013 F\u00e9d\u00e9ration des Caisses Desjardins du Qu\u00e9bec - La Maisonn\u00e9e\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lamaisonnee.org\/fr\/partners\/desjardins\/\" \/>\n<meta property=\"og:site_name\" content=\"La Maisonn\u00e9e\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-09T18:17:07+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lamaisonnee.org\\\/fr\\\/partners\\\/desjardins\\\/\",\"url\":\"https:\\\/\\\/lamaisonnee.org\\\/fr\\\/partners\\\/desjardins\\\/\",\"name\":\"Caisses du C\u0153ur de l\u2019Ile \u2013 F\u00e9d\u00e9ration des Caisses Desjardins du Qu\u00e9bec - La Maisonn\u00e9e\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lamaisonnee.org\\\/fr\\\/#website\"},\"datePublished\":\"2023-04-27T22:35:47+00:00\",\"dateModified\":\"2023-05-09T18:17:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lamaisonnee.org\\\/fr\\\/partners\\\/desjardins\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lamaisonnee.org\\\/fr\\\/partners\\\/desjardins\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lamaisonnee.org\\\/fr\\\/partners\\\/desjardins\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/lamaisonnee.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Caisses du C\u0153ur de l\u2019Ile \u2013 F\u00e9d\u00e9ration des Caisses Desjardins du Qu\u00e9bec\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lamaisonnee.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/lamaisonnee.org\\\/fr\\\/\",\"name\":\"La Maisonn\u00e9e\",\"description\":\"Aide aux immigrants\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lamaisonnee.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Caisses du C\u0153ur de l\u2019Ile \u2013 F\u00e9d\u00e9ration des Caisses Desjardins du Qu\u00e9bec - La Maisonn\u00e9e","robots":{"index":"noindex","follow":"follow"},"og_locale":"fr_FR","og_type":"article","og_title":"Caisses du C\u0153ur de l\u2019Ile \u2013 F\u00e9d\u00e9ration des Caisses Desjardins du Qu\u00e9bec - La Maisonn\u00e9e","og_url":"https:\/\/lamaisonnee.org\/fr\/partners\/desjardins\/","og_site_name":"La Maisonn\u00e9e","article_modified_time":"2023-05-09T18:17:07+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/lamaisonnee.org\/fr\/partners\/desjardins\/","url":"https:\/\/lamaisonnee.org\/fr\/partners\/desjardins\/","name":"Caisses du C\u0153ur de l\u2019Ile \u2013 F\u00e9d\u00e9ration des Caisses Desjardins du Qu\u00e9bec - La Maisonn\u00e9e","isPartOf":{"@id":"https:\/\/lamaisonnee.org\/fr\/#website"},"datePublished":"2023-04-27T22:35:47+00:00","dateModified":"2023-05-09T18:17:07+00:00","breadcrumb":{"@id":"https:\/\/lamaisonnee.org\/fr\/partners\/desjardins\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lamaisonnee.org\/fr\/partners\/desjardins\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/lamaisonnee.org\/fr\/partners\/desjardins\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/lamaisonnee.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Caisses du C\u0153ur de l\u2019Ile \u2013 F\u00e9d\u00e9ration des Caisses Desjardins du Qu\u00e9bec"}]},{"@type":"WebSite","@id":"https:\/\/lamaisonnee.org\/fr\/#website","url":"https:\/\/lamaisonnee.org\/fr\/","name":"La Maisonn\u00e9e","description":"Aide aux immigrants","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lamaisonnee.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/lamaisonnee.org\/fr\/wp-json\/wp\/v2\/partners\/304","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lamaisonnee.org\/fr\/wp-json\/wp\/v2\/partners"}],"about":[{"href":"https:\/\/lamaisonnee.org\/fr\/wp-json\/wp\/v2\/types\/partners"}],"wp:attachment":[{"href":"https:\/\/lamaisonnee.org\/fr\/wp-json\/wp\/v2\/media?parent=304"}],"wp:term":[{"taxonomy":"cat_partner","embeddable":true,"href":"https:\/\/lamaisonnee.org\/fr\/wp-json\/wp\/v2\/cat_partner?post=304"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}